{"id":1169,"count":1,"description":"","link":"https:\/\/jenniepalluzzi.com\/blog\/tag\/underwater-sunshine\/","name":"underwater sunshine","slug":"underwater-sunshine","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/jenniepalluzzi.com\/blog\/wp-json\/wp\/v2\/tags\/1169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jenniepalluzzi.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jenniepalluzzi.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jenniepalluzzi.com\/blog\/wp-json\/wp\/v2\/posts?tags=1169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}